{"id":27114,"date":"2025-03-23T15:01:43","date_gmt":"2025-03-23T15:01:43","guid":{"rendered":"https:\/\/avesaguiar.ch\/produit\/petsafe-drinkwell-platinum-trinkbrunnen-fuer-haustiere-5l-pet-solutions\/"},"modified":"2025-03-23T15:01:43","modified_gmt":"2025-03-23T15:01:43","slug":"petsafe-drinkwell-platinum-trinkbrunnen-fuer-haustiere-5l-pet-solutions","status":"publish","type":"product","link":"https:\/\/avesaguiar.ch\/de\/produit\/petsafe-drinkwell-platinum-trinkbrunnen-fuer-haustiere-5l-pet-solutions\/","title":{"rendered":"PetSafe Drinkwell Platinum Trinkbrunnen f\u00fcr Haustiere 5L &#8211; Pet Solutions"},"content":{"rendered":"<p>Der Drinkwell\u00ae Platinum Haustierbrunnen verf\u00fcgt \u00fcber denselben patentierten Wasserfall wie der Drinkwell\u00ae Original Haustierbrunnen.<\/p>\n<p>Flie\u00dfendes Wasser regt die Tiere an, mehr zu trinken, damit sie fr\u00f6hlich, hydratisiert und gesund bleiben.<\/p>\n<p>Der Platinum Brunnen hat auch einen neuen Klappdeckel, der ein unbeabsichtigtes Entfernen verhindert, einen Vorfilter, der gro\u00dfe Partikel abf\u00e4ngt, bevor sie den Motor erreichen, und eine Tauchpumpe f\u00fcr einen nahezu ger\u00e4uschlosen Betrieb.<br \/>\nSchalengr\u00f6\u00dfe<br \/>\n5 Liter Wasser fassen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Drinkwell\u00ae Platinum Haustierbrunnen verf\u00fcgt \u00fcber denselben patentierten Wasserfall wie der Drinkwell\u00ae Original Haustierbrunnen. Flie\u00dfendes Wasser regt die Tiere an, mehr zu trinken, damit sie fr\u00f6hlich, hydratisiert und gesund bleiben. Der Platinum Brunnen hat auch einen neuen Klappdeckel, der ein unbeabsichtigtes Entfernen verhindert, einen Vorfilter, der gro\u00dfe Partikel abf\u00e4ngt, bevor sie den Motor erreichen, und [&hellip;]<\/p>\n","protected":false},"featured_media":25430,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[187],"product_cat":[267,276,269,277],"product_tag":[],"class_list":["post-27114","product","type-product","status-publish","has-post-thumbnail","product_brand-kinlys","product_cat-hund","product_cat-katzen","product_cat-zubehor","product_cat-zubehor-2","first","instock","shipping-taxable","purchasable","product-type-simple"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/avesaguiar.ch\/de\/wp-json\/wp\/v2\/product\/27114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/avesaguiar.ch\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/avesaguiar.ch\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/avesaguiar.ch\/de\/wp-json\/wp\/v2\/comments?post=27114"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/avesaguiar.ch\/de\/wp-json\/wp\/v2\/media\/25430"}],"wp:attachment":[{"href":"https:\/\/avesaguiar.ch\/de\/wp-json\/wp\/v2\/media?parent=27114"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/avesaguiar.ch\/de\/wp-json\/wp\/v2\/product_brand?post=27114"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/avesaguiar.ch\/de\/wp-json\/wp\/v2\/product_cat?post=27114"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/avesaguiar.ch\/de\/wp-json\/wp\/v2\/product_tag?post=27114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}